{"id":6159,"date":"2018-11-21T16:52:22","date_gmt":"2018-11-21T15:52:22","guid":{"rendered":"https:\/\/gs-weener.de\/cms\/?page_id=6159"},"modified":"2019-01-28T17:22:56","modified_gmt":"2019-01-28T16:22:56","slug":"begabtenfoerderung-englisch","status":"publish","type":"page","link":"https:\/\/gs-weener.de\/cms\/begabtenfoerderung-englisch\/","title":{"rendered":"Englisch"},"content":{"rendered":"<p>Einmal w\u00f6chentlich k\u00f6nnen Sch\u00fcler, die eine gewisse Sprachbegabung aufweisen und besonderes Interesse am Erlernen der englischen Sprache zeigen, freiwillig an einer zus\u00e4tzlichen Englischstunde teilnehmen.<br \/>\nDiese findet klassen\u00fcbergreifend jeweils f\u00fcr Dritt- und Viertkl\u00e4ssler statt. Am Anfang \u00fcben wir mit kurzen Reimen, Liedern und Geschichten unter anderem die Aussprache und erweitern und festigen das englische Vokabular. Wir h\u00f6ren bekannte und fremde Geschichten, die von Muttersprachlern aufgenommen wurden. Das sind B\u00fccher wie &#8222;Little Riding Hood&#8220;, &#8230;<br \/>\nDie Sch\u00fcler lernen die Geschichten zu lesen und im Rollenspiel vorzutragen.<br \/>\nZu besonderen Anl\u00e4ssen f\u00fchren die Kinder kurze englische Sketche auf oder lesen kurze englische Texte oder Gedichte vor.<\/p>\n<p><img decoding=\"async\" class=\"details-image\" draggable=\"false\" src=\"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2019\/01\/P1080596.jpg\" alt=\"\" \/><\/p>\n<p>Im Januar besuchte uns Abi aus England. Sie nahm an einem Sch\u00fcleraustausch mit dem TGG in Leer teil und absolvierte bei uns ein einw\u00f6chiges Praktikum.<\/p>\n<p><u><b>Interview mit Abi<\/b><\/u><\/p>\n<p>Wie hei\u00dft du? \u2013 Abi<\/p>\n<p>Wie alt bist du? \u2013 16 Jahre<\/p>\n<p>Hast du Geschwister? -ja, einen Bruder<\/p>\n<p>Wo wohnst du? \u2013 in London, der Hauptstadt von England<\/p>\n<p>Was ist deine Lieblingsfarbe? -rot<\/p>\n<p>Was ist dein Lieblingsessen? -Pizza<\/p>\n<p>Was ist dein Lieblingstier? &#8211; Katze<\/p>\n<p>Welches ist dein Lieblings-Freizeitpark? &#8211; der Thorpe-Park in London<\/p>\n<p>Was machst du in deiner Freizeit? -Tennis spielen, lesen, Freundinnen treffen, Filme sehen<\/p>\n<p>Welche Schule besuchst du? \u2013 eine M\u00e4dchenschule in London<\/p>\n<p>Wie lange dauert bei euch der Unterricht? -von 8.30 bis 15.00 Uhr<\/p>\n<p>Hast du schon einmal die Queen gesehen? \u2013 nein<\/p>\n<p>Hast du schon Big Ben gesehen? \u2013 ja, nat\u00fcrlich, schon oft<\/p>\n<p>Gibt es viele U-Bahnen in London? -ja<\/p>\n<p>Gibt es nur Doppeldecker-Busse, oder auch normale? -auch normale<\/p>\n<p>Bist du schon im Doppeldecker gefahren? \u2013 ja, schon oft<\/p>\n<p>Wie lange bist du jetzt in Deutschland? -f\u00fcr eine Woche<\/p>\n<p>Wie lange hat die Fahrt hierher gedauert? \u2013 wir sind eine Stunde geflogen (von London nach Bremen) und zwei Stunden mit dem Zug gefahren (von Bremen nach Leer)<\/p>\n<p>Wohnst du hier im Hotel? \u2013 nein, in der Familie meiner Austauschsch\u00fclerin<\/p>\n<p>Seit wann lernst du schon Deutsch? -seit sechs Jahren<\/p>\n<p>Sprichst du noch andere Sprachen? -ja, au\u00dfer Englisch und Deutsch spreche ich noch Franz\u00f6sisch und Spanisch<\/p>\n<p><a name=\"_GoBack\"><\/a> Bist du schon in anderen L\u00e4ndern gewesen? -ja, in Spanien, Italien, Frankreich, Holland, Griechenland und Japan<\/p>\n<p>Welches Essen ist typisch englisch? -Fish and Chips und Tee ist typisch englisch<\/p>\n<p>Trinkt ihr den Tee auch mit Kandis und Sahne? -nein, wir trinken ihn mit viel Milch und Zucker<\/p>\n<p><b>Danke f\u00fcr das Interview<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Einmal w\u00f6chentlich k\u00f6nnen Sch\u00fcler, die eine gewisse Sprachbegabung aufweisen und besonderes Interesse am Erlernen der englischen Sprache zeigen, freiwillig an einer zus\u00e4tzlichen Englischstunde teilnehmen. Diese findet klassen\u00fcbergreifend jeweils f\u00fcr Dritt- und Viertkl\u00e4ssler statt. Am Anfang \u00fcben wir mit kurzen Reimen, Liedern und Geschichten unter anderem die Aussprache und erweitern und festigen das englische Vokabular. Wir [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6159","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/pages\/6159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/comments?post=6159"}],"version-history":[{"count":4,"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/pages\/6159\/revisions"}],"predecessor-version":[{"id":6293,"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/pages\/6159\/revisions\/6293"}],"wp:attachment":[{"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/media?parent=6159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}