{"id":5029,"date":"2016-12-14T20:31:07","date_gmt":"2016-12-14T19:31:07","guid":{"rendered":"http:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008.jpg"},"modified":"2016-12-14T20:31:07","modified_gmt":"2016-12-14T19:31:07","slug":"weihnachtsfeiern-16-008","status":"inherit","type":"attachment","link":"https:\/\/gs-weener.de\/cms\/2016\/12\/weihnachten-2016\/weihnachtsfeiern-16-008\/","title":{"rendered":"weihnachtsfeiern 16 008"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-5029","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008-300x225.jpg 300w, https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008-768x576.jpg 768w, https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008.jpg 980w, https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008-624x468.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":980,"height":735,"file":"2016\/12\/weihnachtsfeiern-16-008.jpg","sizes":{"thumbnail":{"file":"weihnachtsfeiern-16-008-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008-150x150.jpg"},"medium":{"file":"weihnachtsfeiern-16-008-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008-300x225.jpg"},"medium_large":{"file":"weihnachtsfeiern-16-008-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008-768x576.jpg"},"large":{"file":"weihnachtsfeiern-16-008-980x735.jpg","width":980,"height":735,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008-980x735.jpg"},"post-thumbnail":{"file":"weihnachtsfeiern-16-008-624x468.jpg","width":624,"height":468,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008-624x468.jpg"},"full":{"file":"weihnachtsfeiern-16-008.jpg","width":980,"height":735,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008.jpg"}},"image_meta":{"aperture":"2.8","credit":"","camera":"DMC-FS10","caption":"","created_timestamp":"1481619711","copyright":"","focal_length":"5","iso":"1000","shutter_speed":"0.066666666666667","title":"","orientation":"1","keywords":[]}},"post":5021,"source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2016\/12\/weihnachtsfeiern-16-008.jpg","filename":"weihnachtsfeiern-16-008.jpg","filesize":178180,"_links":{"self":[{"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/media\/5029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/comments?post=5029"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":5021,"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/posts\/5021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}