{"id":455,"date":"2013-01-30T17:24:50","date_gmt":"2013-01-30T16:24:50","guid":{"rendered":"http:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2012\/12\/schnee-001.jpg"},"modified":"2013-01-30T17:24:50","modified_gmt":"2013-01-30T16:24:50","slug":"schnee-001","status":"inherit","type":"attachment","link":"https:\/\/gs-weener.de\/cms\/unsere-schule\/wir-machen-die-musik\/schnee-001\/","title":{"rendered":"schnee 001"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"class_list":["post-455","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2012\/12\/schnee-001-e1359563121750.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2012\/12\/schnee-001-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2012\/12\/schnee-001-300x225.jpg 300w, https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2012\/12\/schnee-001-980x735.jpg 980w, https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2012\/12\/schnee-001-624x468.jpg 624w, https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2012\/12\/schnee-001-e1359563121750.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":500,"height":375,"file":"2012\/12\/schnee-001-e1359563121750.jpg","sizes":{"thumbnail":{"file":"schnee-001-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2012\/12\/schnee-001-150x150.jpg"},"medium":{"file":"schnee-001-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2012\/12\/schnee-001-300x225.jpg"},"large":{"file":"schnee-001-980x735.jpg","width":980,"height":735,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2012\/12\/schnee-001-980x735.jpg"},"post-thumbnail":{"file":"schnee-001-624x468.jpg","width":624,"height":468,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2012\/12\/schnee-001-624x468.jpg"},"full":{"file":"schnee-001-e1359563121750.jpg","width":500,"height":375,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2012\/12\/schnee-001-e1359563121750.jpg"}},"image_meta":{"aperture":5.6,"credit":"","camera":"DMC-FS10","caption":"","created_timestamp":1358860714,"copyright":"","focal_length":"18","iso":"800","shutter_speed":"0.033333333333333","title":""}},"post":124,"source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2012\/12\/schnee-001-e1359563121750.jpg","filename":"schnee-001-e1359563121750.jpg","filesize":35693,"_links":{"self":[{"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/media\/455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/comments?post=455"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":124,"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/pages\/124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}