{"id":1451,"date":"2014-01-08T16:49:57","date_gmt":"2014-01-08T15:49:57","guid":{"rendered":"http:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2014\/01\/weihnachtsfeiern-2013-002.jpg"},"modified":"2014-01-08T16:49:57","modified_gmt":"2014-01-08T15:49:57","slug":"weihnachtsfeiern-2013-002","status":"inherit","type":"attachment","link":"https:\/\/gs-weener.de\/cms\/weihnachtsfeiern-2013-002\/","title":{"rendered":"weihnachtsfeiern 2013 002"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"class_list":["post-1451","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2014\/01\/weihnachtsfeiern-2013-002.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2014\/01\/weihnachtsfeiern-2013-002-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2014\/01\/weihnachtsfeiern-2013-002-300x200.jpg 300w, https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2014\/01\/weihnachtsfeiern-2013-002-624x417.jpg 624w, https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2014\/01\/weihnachtsfeiern-2013-002.jpg 980w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":980,"height":655,"file":"2014\/01\/weihnachtsfeiern-2013-002.jpg","sizes":{"thumbnail":{"file":"weihnachtsfeiern-2013-002-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2014\/01\/weihnachtsfeiern-2013-002-150x150.jpg"},"medium":{"file":"weihnachtsfeiern-2013-002-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2014\/01\/weihnachtsfeiern-2013-002-300x200.jpg"},"post-thumbnail":{"file":"weihnachtsfeiern-2013-002-624x417.jpg","width":624,"height":417,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2014\/01\/weihnachtsfeiern-2013-002-624x417.jpg"},"full":{"file":"weihnachtsfeiern-2013-002.jpg","width":980,"height":655,"mime_type":"image\/jpeg","source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2014\/01\/weihnachtsfeiern-2013-002.jpg"}},"image_meta":{"aperture":2.8,"credit":"","camera":"DMC-FS10","caption":"","created_timestamp":1387270212,"copyright":"","focal_length":"5","iso":"400","shutter_speed":"0.125","title":""}},"post":null,"source_url":"https:\/\/gs-weener.de\/cms\/wp-content\/uploads\/2014\/01\/weihnachtsfeiern-2013-002.jpg","filename":"weihnachtsfeiern-2013-002.jpg","filesize":178072,"_links":{"self":[{"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/media\/1451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gs-weener.de\/cms\/wp-json\/wp\/v2\/comments?post=1451"}]}}